{"id":26388,"date":"2024-10-11T10:53:29","date_gmt":"2024-10-11T08:53:29","guid":{"rendered":"https:\/\/www.ildammuso.com\/?p=26388"},"modified":"2024-10-11T10:53:31","modified_gmt":"2024-10-11T08:53:31","slug":"rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana","status":"publish","type":"post","link":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/","title":{"rendered":"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#8217;esperienza quotidiana"},"content":{"rendered":"\n<p>Hannah Arendt diceva che gli esseri umani sono stati fatti per &#8220;nascere&#8221;.<\/p>\n\n\n\n<p>Nascere ripetutamente nel corso della loro vita.<\/p>\n\n\n\n<p>L&#8217;esatto opposto d\u00ec ci\u00f2 che pensava il suo maestro (nonch\u00e9 amante) Martin Heidegger.<\/p>\n\n\n\n<p>Per lui l&#8217;unico destino, compiuto e degno, di un essere umano \u00e8 la sua fine.<\/p>\n\n\n\n<p>Cosa significa &#8220;nascere&#8221; pi\u00f9 volte?<\/p>\n\n\n\n<p>Certe volte vuol dire semplicemente svegliarsi ogni mattina.<br>Che sembra scontato ma non lo \u00e8 fino in fondo.<\/p>\n\n\n\n<p>\u00c8 sforzarsi di fare in modo che ogni giornata acquisisca il sapore di un valore che va ad aggiungere e non a sottrarre.<\/p>\n\n\n\n<p><br>Io rinasco tutte le volte che, tra la fusoliera e l\u2019elica di un bimotore, intravedo la sagoma di Pantelleria.<\/p>\n\n\n\n<p>Rinascere pu\u00f2 significare innamorarsi, ogni giorno, di chi ami o di qualcosa che ami.<\/p>\n\n\n\n<p>Se cedi allo stupore rinasci.<br>Quando progetti e sogni rinasci.<\/p>\n\n\n\n<p>Se accarezzi un cane o un bambino rinasci.<br><\/p>\n\n\n\n<p>Sei viva tutte le volte che la tua risata esce a cascata insieme alle lacrime.<br>Rinasci tutte le volte che incontri una frase in un libro e la segni, perch\u00e9 quella frase \u201cti ha scovata\u201d.<\/p>\n\n\n\n<p>Io rinasco ogni volta che la Piana della Ghirlanda mi viene incontro.<br>Se mia sorella mi abbraccia rinasco.<br>Nel sorriso felice di un ospite che mi saluta io, ogni volta, rinasco.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hannah Arendt diceva che gli esseri umani sono stati fatti [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[441,439],"tags":[1506,1504,1507,958,228,91,792],"class_list":["post-26388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pippe","category-riflessioni-da-pantelleria","tag-vivere","tag-nascere","tag-bambino","tag-colori","tag-ildammuso","tag-pantelleria","tag-vita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#039;esperienza quotidiana | Il Dammuso<\/title>\n<meta name=\"description\" content=\"&quot;Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#039;esperienza quotidiana&quot;: leggi nel blog de Il Dammuso!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#039;esperienza quotidiana | Il Dammuso\" \/>\n<meta property=\"og:description\" content=\"&quot;Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#039;esperienza quotidiana&quot;: leggi nel blog de Il Dammuso!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Dammuso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ildammusodipantelleria\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T08:53:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-11T08:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/\"},\"author\":{\"name\":\"claudia\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#\\\/schema\\\/person\\\/a97bc2634c1ae772b6efbb07fef2b3a8\"},\"headline\":\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#8217;esperienza quotidiana\",\"datePublished\":\"2024-10-11T08:53:29+00:00\",\"dateModified\":\"2024-10-11T08:53:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/\"},\"wordCount\":226,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/nascere-arendt-scaled.jpg\",\"keywords\":[\"vivere\",\"nascere\",\"bambino\",\"colori\",\"ildammuso\",\"pantelleria\",\"vita\"],\"articleSection\":[\"Pippe d'altura\",\"Riflessioni da Pantelleria\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/\",\"url\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/\",\"name\":\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana | Il Dammuso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/nascere-arendt-scaled.jpg\",\"datePublished\":\"2024-10-11T08:53:29+00:00\",\"dateModified\":\"2024-10-11T08:53:31+00:00\",\"description\":\"\\\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana\\\": leggi nel blog de Il Dammuso!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/nascere-arendt-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/nascere-arendt-scaled.jpg\",\"width\":2560,\"height\":1928,\"caption\":\"oplus_0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&nbsp;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/\",\"name\":\"Il Dammuso\",\"description\":\"Il tuo Dammuso a Pantelleria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#organization\",\"name\":\"Il Dammuso\",\"url\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-ildammuso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ildammuso.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo-ildammuso.jpg\",\"width\":426,\"height\":395,\"caption\":\"Il Dammuso\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ildammusodipantelleria\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ildammusogram\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ildammuso.com\\\/it\\\/#\\\/schema\\\/person\\\/a97bc2634c1ae772b6efbb07fef2b3a8\",\"name\":\"claudia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g\",\"caption\":\"claudia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana | Il Dammuso","description":"\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana\": leggi nel blog de Il Dammuso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/","og_locale":"it_IT","og_type":"article","og_title":"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana | Il Dammuso","og_description":"\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana\": leggi nel blog de Il Dammuso!","og_url":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/","og_site_name":"Il Dammuso","article_publisher":"https:\/\/www.facebook.com\/ildammusodipantelleria\/","article_published_time":"2024-10-11T08:53:29+00:00","article_modified_time":"2024-10-11T08:53:31+00:00","og_image":[{"width":2560,"height":1928,"url":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg","type":"image\/jpeg"}],"author":"claudia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"claudia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#article","isPartOf":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/"},"author":{"name":"claudia","@id":"https:\/\/www.ildammuso.com\/it\/#\/schema\/person\/a97bc2634c1ae772b6efbb07fef2b3a8"},"headline":"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l&#8217;esperienza quotidiana","datePublished":"2024-10-11T08:53:29+00:00","dateModified":"2024-10-11T08:53:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/"},"wordCount":226,"publisher":{"@id":"https:\/\/www.ildammuso.com\/it\/#organization"},"image":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#primaryimage"},"thumbnailUrl":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg","keywords":["vivere","nascere","bambino","colori","ildammuso","pantelleria","vita"],"articleSection":["Pippe d'altura","Riflessioni da Pantelleria"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/","url":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/","name":"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana | Il Dammuso","isPartOf":{"@id":"https:\/\/www.ildammuso.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#primaryimage"},"image":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#primaryimage"},"thumbnailUrl":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg","datePublished":"2024-10-11T08:53:29+00:00","dateModified":"2024-10-11T08:53:31+00:00","description":"\"Rinascere ogni giorno: il significato profondo del risveglio secondo Hannah Arendt e l'esperienza quotidiana\": leggi nel blog de Il Dammuso!","breadcrumb":{"@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#primaryimage","url":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg","contentUrl":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2024\/10\/nascere-arendt-scaled.jpg","width":2560,"height":1928,"caption":"oplus_0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ildammuso.com\/it\/rinascere-ogni-giorno-il-significato-profondo-del-risveglio-secondo-hannah-arendt-e-lesperienza-quotidiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ildammuso.com\/it\/"},{"@type":"ListItem","position":2,"name":"&nbsp;"}]},{"@type":"WebSite","@id":"https:\/\/www.ildammuso.com\/it\/#website","url":"https:\/\/www.ildammuso.com\/it\/","name":"Il Dammuso","description":"Il tuo Dammuso a Pantelleria","publisher":{"@id":"https:\/\/www.ildammuso.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ildammuso.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ildammuso.com\/it\/#organization","name":"Il Dammuso","url":"https:\/\/www.ildammuso.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ildammuso.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2022\/06\/logo-ildammuso.jpg","contentUrl":"https:\/\/storage1254.cdn-immedia.net\/wp-content\/uploads\/2022\/06\/logo-ildammuso.jpg","width":426,"height":395,"caption":"Il Dammuso"},"image":{"@id":"https:\/\/www.ildammuso.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ildammusodipantelleria\/","https:\/\/www.instagram.com\/ildammusogram\/"]},{"@type":"Person","@id":"https:\/\/www.ildammuso.com\/it\/#\/schema\/person\/a97bc2634c1ae772b6efbb07fef2b3a8","name":"claudia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfa9e85032faeaffeaaafd48c7c09ad8da852ff133d8361db8721aff28093ebe?s=96&d=mm&r=g","caption":"claudia"}}]}},"_links":{"self":[{"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/posts\/26388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/comments?post=26388"}],"version-history":[{"count":1,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/posts\/26388\/revisions"}],"predecessor-version":[{"id":26391,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/posts\/26388\/revisions\/26391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/media\/26389"}],"wp:attachment":[{"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/media?parent=26388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/categories?post=26388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ildammuso.com\/it\/wp-json\/wp\/v2\/tags?post=26388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}